{"id":25635,"count":6,"description":"","link":"https:\/\/axahomesecurity.com\/de\/product-category\/fur-hinterturen-nach-ausen-offnend-256\/turschlosser-272\/projektschlosser-343\/","name":"Projektschlosser","slug":"projektschlosser-343","taxonomy":"product_cat","parent":25624,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Projektschlosser Archives - AXA Home Security \ud83c\udde9\ud83c\uddea<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/axahomesecurity.com\/de\/product-category\/fur-hinterturen-nach-ausen-offnend-256\/turschlosser-272\/projektschlosser-343\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projektschlosser Archives - AXA Home Security \ud83c\udde9\ud83c\uddea\" \/>\n<meta property=\"og:url\" content=\"https:\/\/axahomesecurity.com\/de\/product-category\/fur-hinterturen-nach-ausen-offnend-256\/turschlosser-272\/projektschlosser-343\/\" \/>\n<meta property=\"og:site_name\" content=\"AXA Home Security \ud83c\udde9\ud83c\uddea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/product-category\\\/fur-hinterturen-nach-ausen-offnend-256\\\/turschlosser-272\\\/projektschlosser-343\\\/\",\"url\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/product-category\\\/fur-hinterturen-nach-ausen-offnend-256\\\/turschlosser-272\\\/projektschlosser-343\\\/\",\"name\":\"Projektschlosser Archives - AXA Home Security \ud83c\udde9\ud83c\uddea\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/product-category\\\/fur-hinterturen-nach-ausen-offnend-256\\\/turschlosser-272\\\/projektschlosser-343\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/product-category\\\/fur-hinterturen-nach-ausen-offnend-256\\\/turschlosser-272\\\/projektschlosser-343\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"house\",\"item\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produkte\",\"item\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/produkte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"f\u00fcr Hintert\u00fcren (nach au\u00dfen \u00f6ffnend)\",\"item\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/product-category\\\/fur-hinterturen-nach-ausen-offnend-256\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"T\u00fcrschl\u00f6sser\",\"item\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/product-category\\\/fur-hinterturen-nach-ausen-offnend-256\\\/turschlosser-272\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Projektschlosser\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/\",\"name\":\"AXA Home\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Projektschlosser Archives - AXA Home Security \ud83c\udde9\ud83c\uddea","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/axahomesecurity.com\/de\/product-category\/fur-hinterturen-nach-ausen-offnend-256\/turschlosser-272\/projektschlosser-343\/","og_locale":"en_US","og_type":"article","og_title":"Projektschlosser Archives - AXA Home Security \ud83c\udde9\ud83c\uddea","og_url":"https:\/\/axahomesecurity.com\/de\/product-category\/fur-hinterturen-nach-ausen-offnend-256\/turschlosser-272\/projektschlosser-343\/","og_site_name":"AXA Home Security \ud83c\udde9\ud83c\uddea","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/axahomesecurity.com\/de\/product-category\/fur-hinterturen-nach-ausen-offnend-256\/turschlosser-272\/projektschlosser-343\/","url":"https:\/\/axahomesecurity.com\/de\/product-category\/fur-hinterturen-nach-ausen-offnend-256\/turschlosser-272\/projektschlosser-343\/","name":"Projektschlosser Archives - AXA Home Security \ud83c\udde9\ud83c\uddea","isPartOf":{"@id":"https:\/\/axahomesecurity.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/axahomesecurity.com\/de\/product-category\/fur-hinterturen-nach-ausen-offnend-256\/turschlosser-272\/projektschlosser-343\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/axahomesecurity.com\/de\/product-category\/fur-hinterturen-nach-ausen-offnend-256\/turschlosser-272\/projektschlosser-343\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"house","item":"https:\/\/axahomesecurity.com\/de\/"},{"@type":"ListItem","position":2,"name":"Produkte","item":"https:\/\/axahomesecurity.com\/de\/produkte\/"},{"@type":"ListItem","position":3,"name":"f\u00fcr Hintert\u00fcren (nach au\u00dfen \u00f6ffnend)","item":"https:\/\/axahomesecurity.com\/de\/product-category\/fur-hinterturen-nach-ausen-offnend-256\/"},{"@type":"ListItem","position":4,"name":"T\u00fcrschl\u00f6sser","item":"https:\/\/axahomesecurity.com\/de\/product-category\/fur-hinterturen-nach-ausen-offnend-256\/turschlosser-272\/"},{"@type":"ListItem","position":5,"name":"Projektschlosser"}]},{"@type":"WebSite","@id":"https:\/\/axahomesecurity.com\/de\/#website","url":"https:\/\/axahomesecurity.com\/de\/","name":"AXA Home","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/axahomesecurity.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/axahomesecurity.com\/de\/wp-json\/wp\/v2\/product_cat\/25635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axahomesecurity.com\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/axahomesecurity.com\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/axahomesecurity.com\/de\/wp-json\/wp\/v2\/product_cat\/25624"}],"wp:post_type":[{"href":"https:\/\/axahomesecurity.com\/de\/wp-json\/wp\/v2\/product?product_cat=25635"},{"href":"https:\/\/axahomesecurity.com\/de\/wp-json\/wp\/v2\/downloads?product_cat=25635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}