{"id":38392,"date":"2026-06-11T10:47:43","date_gmt":"2026-06-11T10:47:43","guid":{"rendered":"http:\/\/axahomesecurity.com\/de\/product\/veiligheids-raamsluiting-48\/"},"modified":"2026-06-11T10:47:44","modified_gmt":"2026-06-11T10:47:44","slug":"sicherheits-fensterverschluss-3319-28","status":"publish","type":"product","link":"https:\/\/axahomesecurity.com\/de\/produkte\/sicherheits-fensterverschluss-3319-28\/","title":{"rendered":"Sicherheits-Fensterverschluss 3319"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":87668,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_trash_the_other_posts":false},"product_brand":[],"product_cat":[25829,25685],"product_tag":[],"class_list":["post-38392","product","type-product","status-publish","has-post-thumbnail","product_cat-fensterverschlusse-mit-zylinderverschluss-622","product_cat-fensterverschlusse-mit-zylinderverschluss-381","first","instock","shipping-taxable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sicherheits-Fensterverschluss 3319 - AXA Home Security \ud83c\udde9\ud83c\uddea<\/title>\n<meta name=\"description\" content=\"Abschlie\u00dfbarer Sicherheits-Fensterverschluss f\u00fcr optimale Absicherung.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/axahomesecurity.com\/de\/produkte\/sicherheits-fensterverschluss-3319-28\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sicherheits-Fensterverschluss 3319 - AXA Home Security \ud83c\udde9\ud83c\uddea\" \/>\n<meta property=\"og:description\" content=\"Abschlie\u00dfbarer Sicherheits-Fensterverschluss f\u00fcr optimale Absicherung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/axahomesecurity.com\/de\/produkte\/sicherheits-fensterverschluss-3319-28\/\" \/>\n<meta property=\"og:site_name\" content=\"AXA Home Security \ud83c\udde9\ud83c\uddea\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-11T10:47:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/axahomesecurity.com\/de\/wp-content\/uploads\/sites\/31\/2024\/08\/foto-331962916-sicherheits-fensterverschluss-3319-8713249220307_E0006097.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1181\" \/>\n\t<meta property=\"og:image:height\" content=\"1181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/produkte\\\/sicherheits-fensterverschluss-3319-28\\\/\",\"url\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/produkte\\\/sicherheits-fensterverschluss-3319-28\\\/\",\"name\":\"Sicherheits-Fensterverschluss 3319 - AXA Home Security \ud83c\udde9\ud83c\uddea\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/produkte\\\/sicherheits-fensterverschluss-3319-28\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/produkte\\\/sicherheits-fensterverschluss-3319-28\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/31\\\/2024\\\/08\\\/foto-331962916-sicherheits-fensterverschluss-3319-8713249220307_E0006097.jpg\",\"datePublished\":\"2026-06-11T10:47:43+00:00\",\"dateModified\":\"2026-06-11T10:47:44+00:00\",\"description\":\"Abschlie\u00dfbarer Sicherheits-Fensterverschluss f\u00fcr optimale Absicherung.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/produkte\\\/sicherheits-fensterverschluss-3319-28\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/produkte\\\/sicherheits-fensterverschluss-3319-28\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/produkte\\\/sicherheits-fensterverschluss-3319-28\\\/#primaryimage\",\"url\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/31\\\/2024\\\/08\\\/foto-331962916-sicherheits-fensterverschluss-3319-8713249220307_E0006097.jpg\",\"contentUrl\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/31\\\/2024\\\/08\\\/foto-331962916-sicherheits-fensterverschluss-3319-8713249220307_E0006097.jpg\",\"width\":1181,\"height\":1181},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/produkte\\\/sicherheits-fensterverschluss-3319-28\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"house\",\"item\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produkte\",\"item\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/produkte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sicherheits-Fensterverschluss 3319\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/\",\"name\":\"AXA Home\",\"description\":\"Downloads \",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sicherheits-Fensterverschluss 3319 - AXA Home Security \ud83c\udde9\ud83c\uddea","description":"Abschlie\u00dfbarer Sicherheits-Fensterverschluss f\u00fcr optimale Absicherung.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/axahomesecurity.com\/de\/produkte\/sicherheits-fensterverschluss-3319-28\/","og_locale":"en_US","og_type":"article","og_title":"Sicherheits-Fensterverschluss 3319 - AXA Home Security \ud83c\udde9\ud83c\uddea","og_description":"Abschlie\u00dfbarer Sicherheits-Fensterverschluss f\u00fcr optimale Absicherung.","og_url":"https:\/\/axahomesecurity.com\/de\/produkte\/sicherheits-fensterverschluss-3319-28\/","og_site_name":"AXA Home Security \ud83c\udde9\ud83c\uddea","article_modified_time":"2026-06-11T10:47:44+00:00","og_image":[{"width":1181,"height":1181,"url":"https:\/\/axahomesecurity.com\/de\/wp-content\/uploads\/sites\/31\/2024\/08\/foto-331962916-sicherheits-fensterverschluss-3319-8713249220307_E0006097.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/axahomesecurity.com\/de\/produkte\/sicherheits-fensterverschluss-3319-28\/","url":"https:\/\/axahomesecurity.com\/de\/produkte\/sicherheits-fensterverschluss-3319-28\/","name":"Sicherheits-Fensterverschluss 3319 - AXA Home Security \ud83c\udde9\ud83c\uddea","isPartOf":{"@id":"https:\/\/axahomesecurity.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/axahomesecurity.com\/de\/produkte\/sicherheits-fensterverschluss-3319-28\/#primaryimage"},"image":{"@id":"https:\/\/axahomesecurity.com\/de\/produkte\/sicherheits-fensterverschluss-3319-28\/#primaryimage"},"thumbnailUrl":"https:\/\/axahomesecurity.com\/de\/wp-content\/uploads\/sites\/31\/2024\/08\/foto-331962916-sicherheits-fensterverschluss-3319-8713249220307_E0006097.jpg","datePublished":"2026-06-11T10:47:43+00:00","dateModified":"2026-06-11T10:47:44+00:00","description":"Abschlie\u00dfbarer Sicherheits-Fensterverschluss f\u00fcr optimale Absicherung.","breadcrumb":{"@id":"https:\/\/axahomesecurity.com\/de\/produkte\/sicherheits-fensterverschluss-3319-28\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/axahomesecurity.com\/de\/produkte\/sicherheits-fensterverschluss-3319-28\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/axahomesecurity.com\/de\/produkte\/sicherheits-fensterverschluss-3319-28\/#primaryimage","url":"https:\/\/axahomesecurity.com\/de\/wp-content\/uploads\/sites\/31\/2024\/08\/foto-331962916-sicherheits-fensterverschluss-3319-8713249220307_E0006097.jpg","contentUrl":"https:\/\/axahomesecurity.com\/de\/wp-content\/uploads\/sites\/31\/2024\/08\/foto-331962916-sicherheits-fensterverschluss-3319-8713249220307_E0006097.jpg","width":1181,"height":1181},{"@type":"BreadcrumbList","@id":"https:\/\/axahomesecurity.com\/de\/produkte\/sicherheits-fensterverschluss-3319-28\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"house","item":"https:\/\/axahomesecurity.com\/de\/"},{"@type":"ListItem","position":2,"name":"Produkte","item":"https:\/\/axahomesecurity.com\/de\/produkte\/"},{"@type":"ListItem","position":3,"name":"Sicherheits-Fensterverschluss 3319"}]},{"@type":"WebSite","@id":"https:\/\/axahomesecurity.com\/de\/#website","url":"https:\/\/axahomesecurity.com\/de\/","name":"AXA Home","description":"Downloads ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/axahomesecurity.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/axahomesecurity.com\/de\/wp-json\/wp\/v2\/product\/38392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axahomesecurity.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/axahomesecurity.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/axahomesecurity.com\/de\/wp-json\/wp\/v2\/comments?post=38392"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/axahomesecurity.com\/de\/wp-json\/wp\/v2\/media\/87668"}],"wp:attachment":[{"href":"https:\/\/axahomesecurity.com\/de\/wp-json\/wp\/v2\/media?parent=38392"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/axahomesecurity.com\/de\/wp-json\/wp\/v2\/product_brand?post=38392"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/axahomesecurity.com\/de\/wp-json\/wp\/v2\/product_cat?post=38392"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/axahomesecurity.com\/de\/wp-json\/wp\/v2\/product_tag?post=38392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}