{"id":31611,"date":"2026-03-29T09:26:12","date_gmt":"2026-03-29T09:26:12","guid":{"rendered":"http:\/\/axahomesecurity.com\/de\/product\/deurkruk-38\/"},"modified":"2026-03-29T09:26:13","modified_gmt":"2026-03-29T09:26:13","slug":"drucker-l-4","status":"publish","type":"product","link":"https:\/\/axahomesecurity.com\/de\/produkte\/drucker-l-4\/","title":{"rendered":"Dr\u00fccker L"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":84319,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_trash_the_other_posts":false},"product_brand":[],"product_cat":[25769,25667],"product_tag":[],"class_list":{"0":"post-31611","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-drucker-562","7":"product_cat-turgriffe-367","9":"first","10":"instock","11":"shipping-taxable","12":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dr\u00fccker L - AXA Home Security \ud83c\udde9\ud83c\uddea<\/title>\n<meta name=\"description\" content=\"Stilvoller T\u00fcrdr\u00fccker f\u00fcr Innen- und Au\u00dfent\u00fcren.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/axahomesecurity.com\/de\/produkte\/drucker-l-4\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dr\u00fccker L - AXA Home Security \ud83c\udde9\ud83c\uddea\" \/>\n<meta property=\"og:description\" content=\"Stilvoller T\u00fcrdr\u00fccker f\u00fcr Innen- und Au\u00dfent\u00fcren.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/axahomesecurity.com\/de\/produkte\/drucker-l-4\/\" \/>\n<meta property=\"og:site_name\" content=\"AXA Home Security \ud83c\udde9\ud83c\uddea\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-29T09:26:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/axahomesecurity.com\/de\/wp-content\/uploads\/sites\/31\/2024\/08\/foto-61407111e-t-rdr-cker-l-8713249098449_E0014511.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1181\" \/>\n\t<meta property=\"og:image:height\" content=\"1181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/produkte\\\/drucker-l-4\\\/\",\"url\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/produkte\\\/drucker-l-4\\\/\",\"name\":\"Dr\u00fccker L - AXA Home Security \ud83c\udde9\ud83c\uddea\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/produkte\\\/drucker-l-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/produkte\\\/drucker-l-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/31\\\/2024\\\/08\\\/foto-61407111e-t-rdr-cker-l-8713249098449_E0014511.jpg\",\"datePublished\":\"2026-03-29T09:26:12+00:00\",\"dateModified\":\"2026-03-29T09:26:13+00:00\",\"description\":\"Stilvoller T\u00fcrdr\u00fccker f\u00fcr Innen- und Au\u00dfent\u00fcren.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/produkte\\\/drucker-l-4\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/produkte\\\/drucker-l-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/produkte\\\/drucker-l-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/31\\\/2024\\\/08\\\/foto-61407111e-t-rdr-cker-l-8713249098449_E0014511.jpg\",\"contentUrl\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/31\\\/2024\\\/08\\\/foto-61407111e-t-rdr-cker-l-8713249098449_E0014511.jpg\",\"width\":1181,\"height\":1181},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/produkte\\\/drucker-l-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"house\",\"item\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produkte\",\"item\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/produkte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dr\u00fccker L\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/\",\"name\":\"AXA Home\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/axahomesecurity.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dr\u00fccker L - AXA Home Security \ud83c\udde9\ud83c\uddea","description":"Stilvoller T\u00fcrdr\u00fccker f\u00fcr Innen- und Au\u00dfent\u00fcren.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/axahomesecurity.com\/de\/produkte\/drucker-l-4\/","og_locale":"en_US","og_type":"article","og_title":"Dr\u00fccker L - AXA Home Security \ud83c\udde9\ud83c\uddea","og_description":"Stilvoller T\u00fcrdr\u00fccker f\u00fcr Innen- und Au\u00dfent\u00fcren.","og_url":"https:\/\/axahomesecurity.com\/de\/produkte\/drucker-l-4\/","og_site_name":"AXA Home Security \ud83c\udde9\ud83c\uddea","article_modified_time":"2026-03-29T09:26:13+00:00","og_image":[{"width":1181,"height":1181,"url":"https:\/\/axahomesecurity.com\/de\/wp-content\/uploads\/sites\/31\/2024\/08\/foto-61407111e-t-rdr-cker-l-8713249098449_E0014511.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/axahomesecurity.com\/de\/produkte\/drucker-l-4\/","url":"https:\/\/axahomesecurity.com\/de\/produkte\/drucker-l-4\/","name":"Dr\u00fccker L - AXA Home Security \ud83c\udde9\ud83c\uddea","isPartOf":{"@id":"https:\/\/axahomesecurity.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/axahomesecurity.com\/de\/produkte\/drucker-l-4\/#primaryimage"},"image":{"@id":"https:\/\/axahomesecurity.com\/de\/produkte\/drucker-l-4\/#primaryimage"},"thumbnailUrl":"https:\/\/axahomesecurity.com\/de\/wp-content\/uploads\/sites\/31\/2024\/08\/foto-61407111e-t-rdr-cker-l-8713249098449_E0014511.jpg","datePublished":"2026-03-29T09:26:12+00:00","dateModified":"2026-03-29T09:26:13+00:00","description":"Stilvoller T\u00fcrdr\u00fccker f\u00fcr Innen- und Au\u00dfent\u00fcren.","breadcrumb":{"@id":"https:\/\/axahomesecurity.com\/de\/produkte\/drucker-l-4\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/axahomesecurity.com\/de\/produkte\/drucker-l-4\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/axahomesecurity.com\/de\/produkte\/drucker-l-4\/#primaryimage","url":"https:\/\/axahomesecurity.com\/de\/wp-content\/uploads\/sites\/31\/2024\/08\/foto-61407111e-t-rdr-cker-l-8713249098449_E0014511.jpg","contentUrl":"https:\/\/axahomesecurity.com\/de\/wp-content\/uploads\/sites\/31\/2024\/08\/foto-61407111e-t-rdr-cker-l-8713249098449_E0014511.jpg","width":1181,"height":1181},{"@type":"BreadcrumbList","@id":"https:\/\/axahomesecurity.com\/de\/produkte\/drucker-l-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"house","item":"https:\/\/axahomesecurity.com\/de\/"},{"@type":"ListItem","position":2,"name":"Produkte","item":"https:\/\/axahomesecurity.com\/de\/produkte\/"},{"@type":"ListItem","position":3,"name":"Dr\u00fccker L"}]},{"@type":"WebSite","@id":"https:\/\/axahomesecurity.com\/de\/#website","url":"https:\/\/axahomesecurity.com\/de\/","name":"AXA Home","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/axahomesecurity.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/axahomesecurity.com\/de\/wp-json\/wp\/v2\/product\/31611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/axahomesecurity.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/axahomesecurity.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/axahomesecurity.com\/de\/wp-json\/wp\/v2\/comments?post=31611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/axahomesecurity.com\/de\/wp-json\/wp\/v2\/media\/84319"}],"wp:attachment":[{"href":"https:\/\/axahomesecurity.com\/de\/wp-json\/wp\/v2\/media?parent=31611"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/axahomesecurity.com\/de\/wp-json\/wp\/v2\/product_brand?post=31611"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/axahomesecurity.com\/de\/wp-json\/wp\/v2\/product_cat?post=31611"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/axahomesecurity.com\/de\/wp-json\/wp\/v2\/product_tag?post=31611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}